{"id":117,"count":2,"description":"","link":"https:\/\/neurosolve.net\/index.php\/tag\/arusha\/","name":"arusha","slug":"arusha","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/neurosolve.net\/index.php\/wp-json\/wp\/v2\/tags\/117"}],"collection":[{"href":"https:\/\/neurosolve.net\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/neurosolve.net\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/neurosolve.net\/index.php\/wp-json\/wp\/v2\/posts?tags=117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}